{"id":220,"count":1,"description":"Katalog informasi jual beli container di Indonesia dengan berbagai tipe serta kebutuhan baru dan bekas. Modifikasi menjadi pilihan utama untuk mendapatkan kontainer unik","link":"https:\/\/kontainerindonesia.co.id\/blog\/tag\/beli-container\/","name":"beli container","slug":"beli-container","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/kontainerindonesia.co.id\/blog\/wp-json\/wp\/v2\/tags\/220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kontainerindonesia.co.id\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kontainerindonesia.co.id\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kontainerindonesia.co.id\/blog\/wp-json\/wp\/v2\/posts?tags=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}